{"id":186,"date":"2024-02-15T19:18:52","date_gmt":"2024-02-15T18:18:52","guid":{"rendered":"https:\/\/www.frantoiodeiure.com\/2024\/?page_id=186"},"modified":"2024-02-19T19:10:12","modified_gmt":"2024-02-19T18:10:12","slug":"kitt-assaggio","status":"publish","type":"page","link":"https:\/\/www.frantoiodeiure.com\/2024\/kitt-assaggio\/","title":{"rendered":"Kit Assaggio"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/www.frantoiodeiure.com\/2024\/wp-content\/uploads\/2024\/02\/kitassaggio.png\" alt=\"\" class=\"wp-image-187\" srcset=\"https:\/\/www.frantoiodeiure.com\/2024\/wp-content\/uploads\/2024\/02\/kitassaggio.png 700w, https:\/\/www.frantoiodeiure.com\/2024\/wp-content\/uploads\/2024\/02\/kitassaggio-300x200.png 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Kit Assaggio composto da:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lattina da 5 Litri<\/li>\n\n\n\n<li>3 bottigliette aromatizzate da 0,10 L a scelta fra Limone, Peperoncino, Basilico, Arancio, Aglio, Rosmarino, e Tartufo bianco<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Telefona o ordina per E-mail sarai ricontattato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per ordinare Cod.<strong>&nbsp;KITASS<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kit Assaggio composto da: Telefona o ordina per E-mail sarai ricontattato. Per ordinare Cod.&nbsp;KITASS<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-186","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/pages\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":5,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/pages\/186\/revisions"}],"predecessor-version":[{"id":401,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/pages\/186\/revisions\/401"}],"wp:attachment":[{"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/media?parent=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}