{"id":250,"date":"2024-02-15T23:06:51","date_gmt":"2024-02-15T22:06:51","guid":{"rendered":"https:\/\/www.frantoiodeiure.com\/2024\/?page_id=250"},"modified":"2024-02-15T23:09:50","modified_gmt":"2024-02-15T22:09:50","slug":"ordini-2","status":"publish","type":"page","link":"https:\/\/www.frantoiodeiure.com\/2024\/ordini-2\/","title":{"rendered":"Ordini"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La vendita dei nostri pregiati prodotti non \u00e9 presente nella grande distribuzione (GDO).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vogliamo rivolgerci direttamente ai nostri consumatori, esigenti ed attenti alla qualit\u00e0, alla genuinit\u00e0 del prodotto ed alla prevenzione della propria salute, ma che allo stesso tempo non rinuncia al piacere e al buon gusto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi ordinare l\u2019Olio Extravergine di Oliva De Iure e tutti gli altri prodotti De Iure direttamente tramite email (all\u2019indirizzo \u2013\u00a0<a href=\"mailto:domenicodeiure1974@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">domenicodeiure1974@gmail.com<\/a>), oppure puoi venire a trovarci presso il nostro frantoio oleario, cos\u00ec avremo il piacere di farti assaggiare l\u2019Olio Extravergine di Oliva e avrai la certezza di acquistare il vero Olio Extravergine di Oliva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alla ricezione dell\u2019Ordine sar\u00e0 ricontattato per definire le condizioni di vendita, sempre restando la facolt\u00e0 di Oleificio De Iure s.a.s di fare proprio l\u2019ordine o rifiutarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cell: 3896890905 \u2013 Domenico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 3389389173 \u2013 Donatella<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Modalit\u00e0 di pagamento tramite Contrassegno o Bonifico Bancario, l\u2019ordine verr\u00e0 evaso solamente al riscontro dell\u2019accredito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vendita dei nostri pregiati prodotti non \u00e9 presente nella grande distribuzione (GDO). Vogliamo rivolgerci direttamente ai nostri consumatori, esigenti ed attenti alla qualit\u00e0, alla genuinit\u00e0 del prodotto ed alla prevenzione della propria salute, ma che allo stesso tempo non rinuncia al piacere e al buon gusto. Puoi ordinare l\u2019Olio Extravergine di Oliva De Iure [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":254,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-250","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/pages\/250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/comments?post=250"}],"version-history":[{"count":2,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/pages\/250\/revisions"}],"predecessor-version":[{"id":253,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/pages\/250\/revisions\/253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/media\/254"}],"wp:attachment":[{"href":"https:\/\/www.frantoiodeiure.com\/2024\/wp-json\/wp\/v2\/media?parent=250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}